{"id":3897,"date":"2021-06-24T14:49:33","date_gmt":"2021-06-24T12:49:33","guid":{"rendered":"https:\/\/sarahschlitz.be\/?p=3897"},"modified":"2021-06-28T10:52:47","modified_gmt":"2021-06-28T08:52:47","slug":"trois-manuels-pour-aider-le-corps-medical-dans-la-prise-en-charge-de-victimes-de-violences-intrafamiliales-de-violences-sexuelles-et-de-mutilation-genitales-feminines","status":"publish","type":"post","link":"https:\/\/sarahschlitz.be\/nl\/trois-manuels-pour-aider-le-corps-medical-dans-la-prise-en-charge-de-victimes-de-violences-intrafamiliales-de-violences-sexuelles-et-de-mutilation-genitales-feminines\/","title":{"rendered":"(Fran\u00e7ais) Trois manuels pour aider le corps m\u00e9dical dans la prise en charge de victimes de violences intrafamiliales, de violences sexuelles et de mutilation g\u00e9nitales f\u00e9minines."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-nl\">Onze verontschuldigingen, dit bericht is alleen beschikbaar in <a href=\"https:\/\/sarahschlitz.be\/fr\/wp-json\/wp\/v2\/posts\/3897\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Onze verontschuldigingen, dit bericht is alleen beschikbaar in Fran\u00e7ais.<\/p>\n","protected":false},"author":1769,"featured_media":3903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"<p>Sous ma tutelle<em>, <\/em>celle de <strong>Frank Vandenbroucke <\/strong>(Vooruit), <em>Vice-premier Ministre et Ministre des Affaires sociales et de la Sant\u00e9 publique<\/em>, <strong>l\u2019Institut pour l'\u00c9galit\u00e9 des Femmes et des Hommes <\/strong>(IEFH) et <strong>l\u2019Ordre des M\u00e9decins<\/strong>, en collaboration avec le professeur Dr. <strong>Tom Goffin<\/strong>, nous avons r\u00e9alis\u00e9 3 manuels de bonnes pratiques pour les m\u00e9decins et autres prestataires de soin dans les cas de violences conjugales, de violences sexuelles et de mutilations g\u00e9nitales f\u00e9minines. Devant ces trois probl\u00e9matiques tr\u00e8s complexes, le but est \u00e0 la fois de sensibiliser et renforcer le personnel soignant, quel qu\u2019il soit, lors de la prise en charge des victimes.<\/p><p>Face aux violences intrafamiliales, aux violences sexuelles ou bien lors de risques de mutilations g\u00e9nitales f\u00e9minines, il est primordial que les prestataires de soin sachent reconna\u00eetre les signaux, les appels \u00e0 l\u2019aide et gagner la confiance des victimes. Ils doivent \u00eatre outill\u00e9s pour assurer une aide optimale \u00e0 la victime le cas \u00e9ch\u00e9ant. Ces questions sont malheureusement tr\u00e8s actuelles. Les m\u00e9decins doivent jouer un r\u00f4le clef dans la prise en charge des victimes de ces trois situations.<\/p><p>En tant que m\u00e9decins ils et elles peuvent apporter une contribution importante \u00e0 la lutte contre les mutilations g\u00e9nitales f\u00e9minines, les violences sexuelles ou conjugales, y compris la violence psychologique. Souvent, le personnel soignant fait partie des rares personnes \u00e0 conna\u00eetre certaines situations de violence bas\u00e9e sur le genre ou \u00e0 les avoir constat\u00e9es lui-m\u00eame. Leur r\u00f4le consiste \u00e0 prot\u00e9ger les personnes, m\u00eame si elles ne sont pas en mesure de demander de l\u2019aide elles-m\u00eames. En outre, les \u00e9tudes scientifiques nous apprennent que la plupart des victimes souhaitent que le m\u00e9decin les interroge sur une \u00e9ventuelle situation de violence[1].<\/p><p>[1] UN-MENAMAIS : environ 87% ; FRA violence against women : 93% des femmes en Belgique<\/p><p>\u00a0<\/p><p>Le corps m\u00e9dical est souvent en contact avec des victimes de violence, mais ils h\u00e9sitent parfois \u00e0 agir. Et m\u00eame lorsqu\u2019ils souhaitent assumer cette responsabilit\u00e9 sociale, les questions[2] restent nombreuses pour assurer un suivi correct, telles que \u201cQue puis-je faire si je soup\u00e7onne ou si je constate des signes de violences sexuelles, de violences conjugales ou de mutilation g\u00e9nitale ? Quels soins et quels conseils puis-je offrir \u00e0 la victime ? Quand les signaux justifient-ils une intervention ext\u00e9rieure ? Comment puis-je maintenir autant que possible la relation avec la victime et\/ou sa famille, tout en organisant l'aide et, si n\u00e9cessaire, en intervenant \u00e0 temps pour assurer la s\u00e9curit\u00e9 de chacun ?<\/p><p>\u00a0<\/p><p>\u00a0\u00a0[2] Voir \u00e9galement UN-MENAMAIS<\/p><p>Ces manuels, \u00e0 travers tout un code de signalement \u00e9labor\u00e9 avec pr\u00e9cision, s\u2019efforcent entre autres de r\u00e9pondre \u00e0 ces questions et de fournir au prestaires de soin un cadre pratique prenant en charge des victimes de mutilations g\u00e9nitales f\u00e9minines, violences intrafamiliales ou violences sexuelles.<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[43,33],"tags":[],"class_list":["post-3897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-droits-des-femmes","category-sante"],"acf":[],"_links":{"self":[{"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/posts\/3897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/users\/1769"}],"replies":[{"embeddable":true,"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/comments?post=3897"}],"version-history":[{"count":0,"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/posts\/3897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/media\/3903"}],"wp:attachment":[{"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/media?parent=3897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/categories?post=3897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sarahschlitz.be\/nl\/wp-json\/wp\/v2\/tags?post=3897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}